{"id":209,"count":1,"description":"","link":"https:\/\/teflonx.com\/ko\/%ea%bc%ac%eb%a6%ac%ed%91%9c\/ptfe-%eb%b8%8c%eb%a0%88%ec%9d%b4%eb%94%94%eb%93%9c-%ec%97%b0%eb%a3%8c-%eb%9d%bc%ec%9d%b8\/","name":"PTFE \ube0c\ub808\uc774\ub514\ub4dc \uc5f0\ub8cc \ub77c\uc778","slug":"ptfe-%eb%b8%8c%eb%a0%88%ec%9d%b4%eb%94%94%eb%93%9c-%ec%97%b0%eb%a3%8c-%eb%9d%bc%ec%9d%b8","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/teflonx.com\/ko\/wp-json\/wp\/v2\/tags\/209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teflonx.com\/ko\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/teflonx.com\/ko\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/teflonx.com\/ko\/wp-json\/wp\/v2\/posts?tags=209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}